{"id":12498,"date":"2020-11-18T09:59:41","date_gmt":"2020-11-18T08:59:41","guid":{"rendered":"https:\/\/www.etnaandseaexcursion.com\/?page_id=12498"},"modified":"2026-02-26T15:05:02","modified_gmt":"2026-02-26T14:05:02","slug":"algo-sobre-nos","status":"publish","type":"page","link":"https:\/\/www.etnaandseaexcursion.com\/pt-pt\/algo-sobre-nos\/","title":{"rendered":"Algo sobre n\u00f3s"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"12498\" class=\"elementor elementor-12498\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8f0e65e e-flex e-con-boxed e-con e-parent\" data-id=\"8f0e65e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e38f603 elementor-widget elementor-widget-image\" data-id=\"e38f603\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2024\/06\/804d2217-42d7-45a1-9c3c-9feffe110219.jpg\" class=\"attachment-full size-full wp-image-12857\" alt=\"\" srcset=\"https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2024\/06\/804d2217-42d7-45a1-9c3c-9feffe110219.jpg 1600w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2024\/06\/804d2217-42d7-45a1-9c3c-9feffe110219-600x450.jpg 600w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2024\/06\/804d2217-42d7-45a1-9c3c-9feffe110219-300x225.jpg 300w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2024\/06\/804d2217-42d7-45a1-9c3c-9feffe110219-1024x768.jpg 1024w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2024\/06\/804d2217-42d7-45a1-9c3c-9feffe110219-768x576.jpg 768w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2024\/06\/804d2217-42d7-45a1-9c3c-9feffe110219-1536x1152.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-0a9a6f3 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0a9a6f3\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-208b2bf\" data-id=\"208b2bf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ae440c animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"1ae440c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div>About<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c67547a elementor-widget__width-initial animated-fast elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"c67547a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Algo sobre n\u00f3s...<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a123a2f elementor-widget__width-initial animated-fast elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"a123a2f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;opal-move-up&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"gdlr-core-pbf-element\"><div class=\"gdlr-core-text-box-item gdlr-core-item-pdlr gdlr-core-item-pdb gdlr-core-left-align\"><div class=\"gdlr-core-text-box-item-content\"><p>Necessidade, Vontade e muita Paix\u00e3o pela natureza, a melhor f\u00f3rmula para valorizar o nosso territ\u00f3rio siciliano. Esta \u00e9 a base do nosso projeto de redescobrir todas as belezas escondidas da nossa ilha.<\/p><p>Contacte o nosso operador tur\u00edstico e ele organizar\u00e1 as suas f\u00e9rias de sonho na Sic\u00edlia ou simplesmente reservar\u00e1 um voo, uma casa de f\u00e9rias, um hotel, uma viagem de bote e muito mais.<\/p><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-22c9cf6 e-flex e-con-boxed e-con e-parent\" data-id=\"22c9cf6\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3624fa6 e-con-full e-flex e-con e-child\" data-id=\"3624fa6\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6d7e36f e-con-full e-flex e-con e-child\" data-id=\"6d7e36f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0c4440b elementor-widget elementor-widget-heading\" data-id=\"0c4440b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Andrea Lo Bue<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1462207 elementor-widget elementor-widget-text-editor\" data-id=\"1462207\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Disse que \u201cDiretor\u201d \u00e9 o chef\u00e3o! Com mil ideias, incans\u00e1vel, passaria a vida inteira imerso na natureza. Em 2005, depois de se licenciar em Ci\u00eancias Biol\u00f3gicas, iniciou a sua actividade como Guia Ambiental fundando a &#8220;BIOSICILIA&#8221;. Entre uma excurs\u00e3o e outra, obteve o doutoramento em Ci\u00eancias Ambientais: ambiente e recursos marinhos. Especializado em Biologia Marinha e Desastres Naturais, ap\u00f3s uma experi\u00eancia na Austr\u00e1lia, integra um grupo de investiga\u00e7\u00e3o italiano no Sudeste Asi\u00e1tico. Professor de Ci\u00eancias Integradas em Escolas P\u00fablicas. Em 2014, ao regressar a It\u00e1lia, fundou a ETNA &amp; SEA EXCURSION, adquirindo as qualifica\u00e7\u00f5es de AIGAE Guide, IDEA Diving Instructor, HSA Dive Buddy, CEDIP\/SIAS Scientific Diver. Idiomas falados: INGL\u00caS, ITALIANO<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e65a9c7 elementor-widget elementor-widget-image\" data-id=\"e65a9c7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"980\" height=\"735\" src=\"https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2024\/04\/IMG_3013-1024x768.jpeg\" class=\"attachment-large size-large wp-image-11067\" alt=\"\" srcset=\"https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2024\/04\/IMG_3013-1024x768.jpeg 1024w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2024\/04\/IMG_3013-600x450.jpeg 600w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2024\/04\/IMG_3013-300x225.jpeg 300w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2024\/04\/IMG_3013-768x576.jpeg 768w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2024\/04\/IMG_3013-1536x1152.jpeg 1536w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2024\/04\/IMG_3013.jpeg 2048w\" sizes=\"(max-width: 980px) 100vw, 980px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fce07f4 e-con-full e-flex e-con e-child\" data-id=\"fce07f4\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f8220c4 e-flex e-con-boxed e-con e-parent\" data-id=\"f8220c4\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-43cd29d e-con-full e-flex e-con e-child\" data-id=\"43cd29d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70568ea elementor-widget elementor-widget-heading\" data-id=\"70568ea\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kevin Costa<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9927d9 elementor-widget elementor-widget-text-editor\" data-id=\"f9927d9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Apaixonado por l\u00ednguas e literatura, sempre foi apaixonado pela sua cidade e pelas suas paisagens naturais. Em 2021 formou-se com louvor na Universidade de L\u00ednguas e Literaturas Europeias de Cat\u00e2nia, com especializa\u00e7\u00e3o em ingl\u00eas, espanhol e franc\u00eas. Com ele voc\u00ea n\u00e3o ir\u00e1 para casa de m\u00e3os vazias! Apaixonado por redes sociais e fotografia, entre uma explica\u00e7\u00e3o e outra, ele far\u00e1 quest\u00e3o de enriquecer sua experi\u00eancia com fotos e v\u00eddeos de qualidade. Um dia passado com ele \u00e9 um sorriso garantido. Idiomas italiano, ingl\u00eas, espanhol e franc\u00eas<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3537337 elementor-widget elementor-widget-image\" data-id=\"3537337\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"583\" src=\"https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2024\/04\/gghguyfyu-768x583.jpg\" class=\"attachment-medium_large size-medium_large wp-image-11063\" alt=\"\" srcset=\"https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2024\/04\/gghguyfyu-768x583.jpg 768w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2024\/04\/gghguyfyu-scaled-600x455.jpg 600w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2024\/04\/gghguyfyu-300x228.jpg 300w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2024\/04\/gghguyfyu-1024x777.jpg 1024w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2024\/04\/gghguyfyu-1536x1166.jpg 1536w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2024\/04\/gghguyfyu-2048x1554.jpg 2048w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2024\/04\/gghguyfyu-593x450.jpg 593w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5d219b5 e-con-full e-flex e-con e-child\" data-id=\"5d219b5\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-686e673 elementor-widget elementor-widget-heading\" data-id=\"686e673\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">RUI CUCUNCI<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f60c126 elementor-widget elementor-widget-image\" data-id=\"f60c126\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/Immagine-WhatsApp-2025-02-26-ore-18.51.49_12a63787-1-768x1024.jpg\" class=\"attachment-medium_large size-medium_large wp-image-13307\" alt=\"\" srcset=\"https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/Immagine-WhatsApp-2025-02-26-ore-18.51.49_12a63787-1-768x1024.jpg 768w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/Immagine-WhatsApp-2025-02-26-ore-18.51.49_12a63787-1-600x800.jpg 600w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/Immagine-WhatsApp-2025-02-26-ore-18.51.49_12a63787-1-225x300.jpg 225w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/Immagine-WhatsApp-2025-02-26-ore-18.51.49_12a63787-1-1152x1536.jpg 1152w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/Immagine-WhatsApp-2025-02-26-ore-18.51.49_12a63787-1-338x450.jpg 338w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/Immagine-WhatsApp-2025-02-26-ore-18.51.49_12a63787-1.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb311f4 elementor-widget elementor-widget-text-editor\" data-id=\"eb311f4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Um amor contagiante pela vulcanologia e pela rica hist\u00f3ria da Sic\u00edlia. Desde 2024 que se junta \u00e0 Etna &amp; Sea como guia no espetacular Monte Etna. Depois de viver no estrangeiro, encontrou um lar em Cat\u00e2nia, uma cidade que admira e adora, para seguir o seu sonho de trabalhar no maior vulc\u00e3o ativo da Europa. Sempre entusiasmado e cheio de energia, nunca se cansar\u00e1 de partilhar consigo os mitos e lendas da Sic\u00edlia, tornando cada aventura inesquec\u00edvel. Para al\u00e9m do seu amor pelos vulc\u00f5es, Rui \u00e9 um fot\u00f3grafo apaixonado, h\u00e1bil em captar a beleza das paisagens e do c\u00e9u noturno atrav\u00e9s da astrofotografia.<br \/>L\u00ednguas faladas: ITALIANO, PORTUGU\u00caS, INGL\u00caS, ESPANHOL<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-de66e15 e-flex e-con-boxed e-con e-parent\" data-id=\"de66e15\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a0bb082 e-con-full e-flex e-con e-child\" data-id=\"a0bb082\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d940bb4 elementor-widget elementor-widget-heading\" data-id=\"d940bb4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">RAJI RAMAGET<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7151e5 elementor-widget elementor-widget-image\" data-id=\"d7151e5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/Immagine-WhatsApp-2025-02-28-ore-10.35.11_6e7c7395-768x1024.jpg\" class=\"attachment-medium_large size-medium_large wp-image-13286\" alt=\"\" srcset=\"https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/Immagine-WhatsApp-2025-02-28-ore-10.35.11_6e7c7395-768x1024.jpg 768w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/Immagine-WhatsApp-2025-02-28-ore-10.35.11_6e7c7395-scaled-600x800.jpg 600w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/Immagine-WhatsApp-2025-02-28-ore-10.35.11_6e7c7395-225x300.jpg 225w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/Immagine-WhatsApp-2025-02-28-ore-10.35.11_6e7c7395-1152x1536.jpg 1152w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/Immagine-WhatsApp-2025-02-28-ore-10.35.11_6e7c7395-1536x2048.jpg 1536w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/Immagine-WhatsApp-2025-02-28-ore-10.35.11_6e7c7395-338x450.jpg 338w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/Immagine-WhatsApp-2025-02-28-ore-10.35.11_6e7c7395-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26b9c8b elementor-widget elementor-widget-text-editor\" data-id=\"26b9c8b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Sempre entusiasmado com novas aventuras, apaixonado pela sua terra e pelo vulc\u00e3o Etna. Ele nunca se cansar\u00e1 de lhe contar sobre os mitos e lendas da Sic\u00edlia. De origem \u00edtalo-francesa, passou a inf\u00e2ncia estudando em casa com sua fam\u00edlia ao redor do mundo, viajando da Tun\u00edsia ao Senegal, da \u00cdndia \u00e0 China. De volta \u00e0 Sic\u00edlia, passou a adolesc\u00eancia na vila dos morangos, uma pequena aldeia aos p\u00e9s do Etna, ponto de partida para seus intermin\u00e1veis \u200b\u200bpasseios de bicicleta ao redor do vulc\u00e3o em busca de novas cavernas. Vai morar em Ragusa Ibla (cen\u00e1rio do Inspetor Montalbano) onde estuda l\u00ednguas e trabalha como pizzaiolo. A\u00ed chega a pandemia e ele decide se envolver e seguir seu sonho: dar a conhecer sua terra ao mundo. . Idiomas falados: INGL\u00caS, FRANC\u00caS, ITALIANO.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e68c9ac e-con-full e-flex e-con e-child\" data-id=\"e68c9ac\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c959c4 elementor-widget elementor-widget-heading\" data-id=\"6c959c4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FABIO COSENTINO<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-259db53 elementor-widget elementor-widget-text-editor\" data-id=\"259db53\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Nascido no sop\u00e9 do vulc\u00e3o Etna, admirando as erup\u00e7\u00f5es da varanda de sua casa, desenvolveu uma liga\u00e7\u00e3o quase emocional com \u201cIDDA a Muntagna\u201d. O v\u00ednculo profundo reflete-se no seu trabalho como guia; Entre piadas e gargalhadas ele vai envolv\u00ea-lo com hist\u00f3rias que v\u00e3o da geologia \u00e0 mitologia, n\u00e3o faltar\u00e3o curiosidades \u00fanicas sobre o vulc\u00e3o.<\/p><p>A sua bondade e empatia tornam-no perfeito para deixar qualquer pessoa \u00e0 vontade, fazendo com que se sinta imediatamente em casa. Apaixonado e entusiasmado, ir\u00e1 gui\u00e1-lo na descoberta do vulc\u00e3o, fazendo com que viva uma experi\u00eancia aut\u00eantica e inesquec\u00edvel.<\/p><p>L\u00ednguas faladas: ITALIANO, INGL\u00caS, ESPANHOL<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4901392 elementor-widget elementor-widget-image\" data-id=\"4901392\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1025\" src=\"https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2026\/02\/9058668f-af6b-4162-871b-32831942ea67-768x1025.jpg\" class=\"attachment-medium_large size-medium_large wp-image-14238\" alt=\"\" srcset=\"https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2026\/02\/9058668f-af6b-4162-871b-32831942ea67-768x1025.jpg 768w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2026\/02\/9058668f-af6b-4162-871b-32831942ea67-600x800.jpg 600w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2026\/02\/9058668f-af6b-4162-871b-32831942ea67-225x300.jpg 225w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2026\/02\/9058668f-af6b-4162-871b-32831942ea67-337x450.jpg 337w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2026\/02\/9058668f-af6b-4162-871b-32831942ea67.jpg 946w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e727b8f e-flex e-con-boxed e-con e-parent\" data-id=\"e727b8f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0440a89 e-con-full e-flex e-con e-child\" data-id=\"0440a89\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bcb34eb elementor-widget elementor-widget-heading\" data-id=\"bcb34eb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">fabrizio di stefano<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b257881 elementor-widget elementor-widget-text-editor\" data-id=\"b257881\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Apaixonado por l\u00ednguas estrangeiras e vulcanologia, ir\u00e1 acompanh\u00e1-lo numa viagem \u00fanica para descobrir o majestoso Monte Etna, partilhando o seu conhecimento, curiosidades e o encanto de um dos vulc\u00f5es mais ativos do mundo.<\/p><p>Ap\u00f3s se ter licenciado em 2023 em Media\u00e7\u00e3o Lingu\u00edstica e Intercultural pela Universidade de Catania, deu os primeiros passos como guia de natureza, juntando-se \u00e0 equipa da Etna &amp; Sea Excursions em 2025.<\/p><p>Profundamente ligado \u00e0 sua terra natal, ele falar-lhe-\u00e1 da Sic\u00edlia n\u00e3o s\u00f3 atrav\u00e9s das suas paisagens espetaculares, mas tamb\u00e9m atrav\u00e9s da sua hist\u00f3ria milenar, tradi\u00e7\u00f5es e mitologia que tornaram a sua ilha t\u00e3o singular.<\/p><p>Com grande entusiasmo e alegria, transformar\u00e1 cada excurs\u00e3o numa experi\u00eancia envolvente, repleta de emo\u00e7\u00e3o, descobertas e encantamento!<\/p><p>L\u00ednguas faladas: ITALIANO, INGL\u00caS E FRANC\u00caS<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-728210f elementor-widget elementor-widget-image\" data-id=\"728210f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-14.57.29-768x576.jpeg\" class=\"attachment-medium_large size-medium_large wp-image-14208\" alt=\"\" srcset=\"https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-14.57.29-768x576.jpeg 768w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-14.57.29-600x450.jpeg 600w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-14.57.29-300x225.jpeg 300w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-14.57.29-1024x768.jpeg 1024w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-14.57.29-1536x1152.jpeg 1536w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2026\/02\/WhatsApp-Image-2026-02-25-at-14.57.29.jpeg 1600w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e9330c7 e-flex e-con-boxed e-con e-parent\" data-id=\"e9330c7\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c9a28bf e-con-full e-flex e-con e-child\" data-id=\"c9a28bf\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b580ef elementor-widget elementor-widget-heading\" data-id=\"5b580ef\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">LAURA MARINELLI<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19ed711 elementor-widget elementor-widget-text-editor\" data-id=\"19ed711\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>A energia dela circula por si, est\u00e1 sempre a sorrir, \u00e9 um rio de ideias a toda a velocidade! S\u00f3 uma mulher siciliana sabe o quanto se parece com todas as personalidades extravagantes da nossa fam\u00edlia. Desde 2014, o BIOSICILIA\/IDEA Nature Guide \u00e9 especializado em turismo aqu\u00e1tico, snorkeling, trekking costeiro e safaris fotogr\u00e1ficos. No mesmo ano, \u00e9 cofundadora da ETNA &amp; SEA EXCURSION. Quando n\u00e3o est\u00e1 envolvida em atividades de campo, \u00e9 respons\u00e1vel pela gest\u00e3o de marketing e webmaster. Para al\u00e9m do ecr\u00e3, dois e-mails, o telefone sempre me encontrar\u00e1, para ser Santificado! L\u00ednguas faladas: ITALIANO, INGL\u00caS.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ef6bbb elementor-widget elementor-widget-image\" data-id=\"9ef6bbb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1365\" src=\"https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/IMG_1415-1-768x1365.jpg\" class=\"attachment-medium_large size-medium_large wp-image-13184\" alt=\"\" srcset=\"https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/IMG_1415-1-768x1365.jpg 768w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/IMG_1415-1-scaled-600x1067.jpg 600w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/IMG_1415-1-169x300.jpg 169w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/IMG_1415-1-576x1024.jpg 576w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/IMG_1415-1-864x1536.jpg 864w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/IMG_1415-1-1152x2048.jpg 1152w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/IMG_1415-1-253x450.jpg 253w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/IMG_1415-1-scaled.jpg 1440w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1ba4073 e-con-full e-flex e-con e-child\" data-id=\"1ba4073\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b00ade6 elementor-widget elementor-widget-heading\" data-id=\"b00ade6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">GAIA FRANCESCHINI<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-348f933 elementor-widget elementor-widget-text-editor\" data-id=\"348f933\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>O nosso gerente de m\u00eddia social. Licenciada em engenharia de gesta\u00e7\u00e3o. Ex-nadadora sincronizada, traz disciplina e criatividade ao seu trabalho. Apaixonada pela natureza e pela comunica\u00e7\u00e3o, tem estrat\u00e9gia e talento para gerir projetos e campanhas inovadoras nas redes sociais. Com o seu esp\u00edrito alegre e determinado, consegue equilibrar as suas responsabilidades profissionais, transmitindo sempre uma positividade contagiante a todos os que conhece. L\u00ednguas faladas: ITALIANO, INGL\u00caS.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b903447 elementor-widget elementor-widget-image\" data-id=\"b903447\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"851\" height=\"1024\" src=\"https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-27-08.35.41-2-851x1024.png\" class=\"attachment-large size-large wp-image-13194\" alt=\"\" srcset=\"https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-27-08.35.41-2-851x1024.png 851w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-27-08.35.41-2-600x722.png 600w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-27-08.35.41-2-249x300.png 249w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-27-08.35.41-2-768x924.png 768w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-27-08.35.41-2-1277x1536.png 1277w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-27-08.35.41-2-374x450.png 374w, https:\/\/www.etnaandseaexcursion.com\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-27-08.35.41-2.png 1637w\" sizes=\"(max-width: 851px) 100vw, 851px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a772af6 e-flex e-con-boxed e-con e-parent\" data-id=\"a772af6\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f7fd52 elementor-widget elementor-widget-heading\" data-id=\"2f7fd52\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dire\u00e7\u00e3o T\u00e9cnica Operador Tur\u00edstico<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-404da27 elementor-widget elementor-widget-text-editor\" data-id=\"404da27\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Asterix Travel di Longo Pietro Paolo<br \/>Via VI Traversa, 57<br \/>95032 Belpasso (CT)<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>About Algo sobre n\u00f3s&#8230; Necessidade, Vontade e muita Paix\u00e3o pela natureza, a melhor f\u00f3rmula para valorizar o nosso territ\u00f3rio siciliano. Esta \u00e9 a base do nosso projeto de redescobrir todas as belezas escondidas da nossa ilha. Contacte o nosso operador tur\u00edstico e ele organizar\u00e1 as suas f\u00e9rias de sonho na Sic\u00edlia ou simplesmente reservar\u00e1 um [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_theme","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-12498","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.etnaandseaexcursion.com\/pt-pt\/wp-json\/wp\/v2\/pages\/12498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.etnaandseaexcursion.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.etnaandseaexcursion.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.etnaandseaexcursion.com\/pt-pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.etnaandseaexcursion.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=12498"}],"version-history":[{"count":54,"href":"https:\/\/www.etnaandseaexcursion.com\/pt-pt\/wp-json\/wp\/v2\/pages\/12498\/revisions"}],"predecessor-version":[{"id":14245,"href":"https:\/\/www.etnaandseaexcursion.com\/pt-pt\/wp-json\/wp\/v2\/pages\/12498\/revisions\/14245"}],"wp:attachment":[{"href":"https:\/\/www.etnaandseaexcursion.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=12498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}